{"id":6508,"date":"2026-05-14T14:22:23","date_gmt":"2026-05-14T14:22:23","guid":{"rendered":"https:\/\/cannabisseedbank.ca\/?post_type=product&#038;p=6508"},"modified":"2026-05-14T14:22:25","modified_gmt":"2026-05-14T14:22:25","slug":"sapphire-desire","status":"publish","type":"product","link":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/","title":{"rendered":"Sapphire Desire"},"content":{"rendered":"<p>Lineage: Black Patronus<br \/>\nReversal: Blueberry Bang Bang<br \/>\nPack Size: 6 Seeds<br \/>\nSex: Feminized<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lineage: Black Patronus Reversal: Blueberry Bang Bang Pack Size: 6 Seeds Sex: Feminized<\/p>\n","protected":false},"featured_media":6477,"comment_status":"open","ping_status":"closed","template":"","meta":[],"pwb-brand":[],"product_cat":[71],"product_tag":[],"class_list":["post-6508","product","type-product","status-publish","has-post-thumbnail","product_cat-exotic-genetix","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sapphire Desire - Canada Seed Bank<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sapphire Desire - Canada Seed Bank\" \/>\n<meta property=\"og:description\" content=\"Lineage: Black Patronus Reversal: Blueberry Bang Bang Pack Size: 6 Seeds Sex: Feminized\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/\" \/>\n<meta property=\"og:site_name\" content=\"Canada Seed Bank\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T14:22:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/\",\"url\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/\",\"name\":\"Sapphire Desire - Canada Seed Bank\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cannabisseedbank.ca\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Exotic-Genetix.jpeg\",\"datePublished\":\"2026-05-14T14:22:23+00:00\",\"dateModified\":\"2026-05-14T14:22:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cannabisseedbank.ca\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Exotic-Genetix.jpeg\",\"contentUrl\":\"https:\\\/\\\/cannabisseedbank.ca\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Exotic-Genetix.jpeg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/product\\\/sapphire-desire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cannabisseedbank.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/cannabisseedbank.ca\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sapphire Desire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/#website\",\"url\":\"https:\\\/\\\/cannabisseedbank.ca\\\/\",\"name\":\"Canada Seed Bank\",\"description\":\"Canada-seed-bank\",\"publisher\":{\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cannabisseedbank.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/#organization\",\"name\":\"Canada Seed Bank\",\"url\":\"https:\\\/\\\/cannabisseedbank.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cannabisseedbank.ca\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/cropped-cropped-cropped-CSB-ID.png\",\"contentUrl\":\"https:\\\/\\\/cannabisseedbank.ca\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/cropped-cropped-cropped-CSB-ID.png\",\"width\":512,\"height\":341,\"caption\":\"Canada Seed Bank\"},\"image\":{\"@id\":\"https:\\\/\\\/cannabisseedbank.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sapphire Desire - Canada Seed Bank","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/","og_locale":"en_US","og_type":"article","og_title":"Sapphire Desire - Canada Seed Bank","og_description":"Lineage: Black Patronus Reversal: Blueberry Bang Bang Pack Size: 6 Seeds Sex: Feminized","og_url":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/","og_site_name":"Canada Seed Bank","article_modified_time":"2026-05-14T14:22:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/","url":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/","name":"Sapphire Desire - Canada Seed Bank","isPartOf":{"@id":"https:\/\/cannabisseedbank.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/#primaryimage"},"image":{"@id":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/#primaryimage"},"thumbnailUrl":"https:\/\/cannabisseedbank.ca\/wp-content\/uploads\/2026\/05\/Exotic-Genetix.jpeg","datePublished":"2026-05-14T14:22:23+00:00","dateModified":"2026-05-14T14:22:25+00:00","breadcrumb":{"@id":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/#primaryimage","url":"https:\/\/cannabisseedbank.ca\/wp-content\/uploads\/2026\/05\/Exotic-Genetix.jpeg","contentUrl":"https:\/\/cannabisseedbank.ca\/wp-content\/uploads\/2026\/05\/Exotic-Genetix.jpeg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/cannabisseedbank.ca\/index.php\/product\/sapphire-desire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cannabisseedbank.ca\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/cannabisseedbank.ca\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Sapphire Desire"}]},{"@type":"WebSite","@id":"https:\/\/cannabisseedbank.ca\/#website","url":"https:\/\/cannabisseedbank.ca\/","name":"Canada Seed Bank","description":"Canada-seed-bank","publisher":{"@id":"https:\/\/cannabisseedbank.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cannabisseedbank.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cannabisseedbank.ca\/#organization","name":"Canada Seed Bank","url":"https:\/\/cannabisseedbank.ca\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cannabisseedbank.ca\/#\/schema\/logo\/image\/","url":"https:\/\/cannabisseedbank.ca\/wp-content\/uploads\/2020\/12\/cropped-cropped-cropped-CSB-ID.png","contentUrl":"https:\/\/cannabisseedbank.ca\/wp-content\/uploads\/2020\/12\/cropped-cropped-cropped-CSB-ID.png","width":512,"height":341,"caption":"Canada Seed Bank"},"image":{"@id":"https:\/\/cannabisseedbank.ca\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"brands":[],"_links":{"self":[{"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/product\/6508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/comments?post=6508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/media\/6477"}],"wp:attachment":[{"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/media?parent=6508"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/pwb-brand?post=6508"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/product_cat?post=6508"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cannabisseedbank.ca\/index.php\/wp-json\/wp\/v2\/product_tag?post=6508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}